{"id":902,"date":"2021-04-06T12:40:00","date_gmt":"2021-04-06T12:40:00","guid":{"rendered":"https:\/\/eplglobal.verifinow.in\/?p=902"},"modified":"2024-07-16T12:41:11","modified_gmt":"2024-07-16T12:41:11","slug":"perseverance-can-achieve-anything","status":"publish","type":"post","link":"https:\/\/eplglobal.verifinow.in\/es\/perseverance-can-achieve-anything\/","title":{"rendered":"La perseverancia puede lograr cualquier cosa"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":891,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"\n<title>Perseverance can achieve anything - EPL - Leading the pack<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perseverance can achieve anything - EPL - Leading the pack\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eplglobal.verifinow.in\/es\/perseverance-can-achieve-anything\/\" \/>\n<meta property=\"og:site_name\" content=\"EPL - Leading the pack\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EPLGlobalLimited\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-06T12:40:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-16T12:41:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eplglobal.verifinow.in\/wp-content\/uploads\/2024\/07\/Untitled-2-300x207-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"207\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin_eplwp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EPL_Limited\" \/>\n<meta name=\"twitter:site\" content=\"@EPL_Limited\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_eplwp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/perseverance-can-achieve-anything\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/perseverance-can-achieve-anything\\\/\"},\"author\":{\"name\":\"admin_eplwp\",\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/#\\\/schema\\\/person\\\/1dcd283e3b2c8dd1cbb342b00411d36e\"},\"headline\":\"Perseverance can achieve anything\",\"datePublished\":\"2021-04-06T12:40:00+00:00\",\"dateModified\":\"2024-07-16T12:41:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/perseverance-can-achieve-anything\\\/\"},\"wordCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/perseverance-can-achieve-anything\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Untitled-2-300x207-1.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/perseverance-can-achieve-anything\\\/\",\"url\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/perseverance-can-achieve-anything\\\/\",\"name\":\"Perseverance can achieve anything - EPL - Leading the pack\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/perseverance-can-achieve-anything\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/perseverance-can-achieve-anything\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Untitled-2-300x207-1.jpg\",\"datePublished\":\"2021-04-06T12:40:00+00:00\",\"dateModified\":\"2024-07-16T12:41:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/perseverance-can-achieve-anything\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eplglobal.verifinow.in\\\/perseverance-can-achieve-anything\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/perseverance-can-achieve-anything\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Untitled-2-300x207-1.jpg\",\"contentUrl\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Untitled-2-300x207-1.jpg\",\"width\":300,\"height\":207},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/perseverance-can-achieve-anything\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perseverance can achieve anything\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/#website\",\"url\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/\",\"name\":\"EPL\",\"description\":\"EPL ltd\",\"publisher\":{\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/#organization\",\"name\":\"EPL Ltd\",\"url\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/EPL-logo-300x207-1-3.png\",\"contentUrl\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/EPL-logo-300x207-1-3.png\",\"width\":300,\"height\":207,\"caption\":\"EPL Ltd\"},\"image\":{\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EPLGlobalLimited\",\"https:\\\/\\\/x.com\\\/EPL_Limited\",\"https:\\\/\\\/www.instagram.com\\\/epl_limited\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/epl-limited\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCciHlQEzUjUqievawSyoNcw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/#\\\/schema\\\/person\\\/1dcd283e3b2c8dd1cbb342b00411d36e\",\"name\":\"admin_eplwp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f14e7ab5f443acaad94261e67d284b5c5212d1a38088925ac84f1633be102fe?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f14e7ab5f443acaad94261e67d284b5c5212d1a38088925ac84f1633be102fe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f14e7ab5f443acaad94261e67d284b5c5212d1a38088925ac84f1633be102fe?s=96&d=mm&r=g\",\"caption\":\"admin_eplwp\"},\"sameAs\":[\"https:\\\/\\\/eplglobal.verifinow.in\"]}]}<\/script>\n","yoast_head_json":{"title":"La perseverancia puede lograr cualquier cosa - EPL - Liderando el grupo","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Perseverance can achieve anything - EPL - Leading the pack","og_url":"https:\/\/eplglobal.verifinow.in\/es\/perseverance-can-achieve-anything\/","og_site_name":"EPL - Leading the pack","article_publisher":"https:\/\/www.facebook.com\/EPLGlobalLimited","article_published_time":"2021-04-06T12:40:00+00:00","article_modified_time":"2024-07-16T12:41:11+00:00","og_image":[{"width":300,"height":207,"url":"https:\/\/eplglobal.verifinow.in\/wp-content\/uploads\/2024\/07\/Untitled-2-300x207-1.jpg","type":"image\/jpeg"}],"author":"admin_eplwp","twitter_card":"summary_large_image","twitter_creator":"@EPL_Limited","twitter_site":"@EPL_Limited","twitter_misc":{"Escrito por":"admin_eplwp"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eplglobal.verifinow.in\/perseverance-can-achieve-anything\/#article","isPartOf":{"@id":"https:\/\/eplglobal.verifinow.in\/perseverance-can-achieve-anything\/"},"author":{"name":"admin_eplwp","@id":"https:\/\/eplglobal.verifinow.in\/#\/schema\/person\/1dcd283e3b2c8dd1cbb342b00411d36e"},"headline":"Perseverance can achieve anything","datePublished":"2021-04-06T12:40:00+00:00","dateModified":"2024-07-16T12:41:11+00:00","mainEntityOfPage":{"@id":"https:\/\/eplglobal.verifinow.in\/perseverance-can-achieve-anything\/"},"wordCount":4,"publisher":{"@id":"https:\/\/eplglobal.verifinow.in\/#organization"},"image":{"@id":"https:\/\/eplglobal.verifinow.in\/perseverance-can-achieve-anything\/#primaryimage"},"thumbnailUrl":"https:\/\/eplglobal.verifinow.in\/wp-content\/uploads\/2024\/07\/Untitled-2-300x207-1.jpg","articleSection":["News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/eplglobal.verifinow.in\/perseverance-can-achieve-anything\/","url":"https:\/\/eplglobal.verifinow.in\/perseverance-can-achieve-anything\/","name":"La perseverancia puede lograr cualquier cosa - EPL - Liderando el grupo","isPartOf":{"@id":"https:\/\/eplglobal.verifinow.in\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eplglobal.verifinow.in\/perseverance-can-achieve-anything\/#primaryimage"},"image":{"@id":"https:\/\/eplglobal.verifinow.in\/perseverance-can-achieve-anything\/#primaryimage"},"thumbnailUrl":"https:\/\/eplglobal.verifinow.in\/wp-content\/uploads\/2024\/07\/Untitled-2-300x207-1.jpg","datePublished":"2021-04-06T12:40:00+00:00","dateModified":"2024-07-16T12:41:11+00:00","breadcrumb":{"@id":"https:\/\/eplglobal.verifinow.in\/perseverance-can-achieve-anything\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eplglobal.verifinow.in\/perseverance-can-achieve-anything\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eplglobal.verifinow.in\/perseverance-can-achieve-anything\/#primaryimage","url":"https:\/\/eplglobal.verifinow.in\/wp-content\/uploads\/2024\/07\/Untitled-2-300x207-1.jpg","contentUrl":"https:\/\/eplglobal.verifinow.in\/wp-content\/uploads\/2024\/07\/Untitled-2-300x207-1.jpg","width":300,"height":207},{"@type":"BreadcrumbList","@id":"https:\/\/eplglobal.verifinow.in\/perseverance-can-achieve-anything\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eplglobal.verifinow.in\/"},{"@type":"ListItem","position":2,"name":"Perseverance can achieve anything"}]},{"@type":"WebSite","@id":"https:\/\/eplglobal.verifinow.in\/#website","url":"https:\/\/eplglobal.verifinow.in\/","name":"Liga Premier Inglesa","description":"EPL Ltd.","publisher":{"@id":"https:\/\/eplglobal.verifinow.in\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eplglobal.verifinow.in\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/eplglobal.verifinow.in\/#organization","name":"EPL Ltd","url":"https:\/\/eplglobal.verifinow.in\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eplglobal.verifinow.in\/#\/schema\/logo\/image\/","url":"https:\/\/eplglobal.verifinow.in\/wp-content\/uploads\/2024\/07\/EPL-logo-300x207-1-3.png","contentUrl":"https:\/\/eplglobal.verifinow.in\/wp-content\/uploads\/2024\/07\/EPL-logo-300x207-1-3.png","width":300,"height":207,"caption":"EPL Ltd"},"image":{"@id":"https:\/\/eplglobal.verifinow.in\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EPLGlobalLimited","https:\/\/x.com\/EPL_Limited","https:\/\/www.instagram.com\/epl_limited\/","https:\/\/www.linkedin.com\/company\/epl-limited\/","https:\/\/www.youtube.com\/channel\/UCciHlQEzUjUqievawSyoNcw"]},{"@type":"Person","@id":"https:\/\/eplglobal.verifinow.in\/#\/schema\/person\/1dcd283e3b2c8dd1cbb342b00411d36e","name":"administrador_eplwp","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6f14e7ab5f443acaad94261e67d284b5c5212d1a38088925ac84f1633be102fe?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6f14e7ab5f443acaad94261e67d284b5c5212d1a38088925ac84f1633be102fe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f14e7ab5f443acaad94261e67d284b5c5212d1a38088925ac84f1633be102fe?s=96&d=mm&r=g","caption":"admin_eplwp"},"sameAs":["https:\/\/eplglobal.verifinow.in"]}]}},"_links":{"self":[{"href":"https:\/\/eplglobal.verifinow.in\/es\/wp-json\/wp\/v2\/posts\/902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eplglobal.verifinow.in\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eplglobal.verifinow.in\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eplglobal.verifinow.in\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eplglobal.verifinow.in\/es\/wp-json\/wp\/v2\/comments?post=902"}],"version-history":[{"count":0,"href":"https:\/\/eplglobal.verifinow.in\/es\/wp-json\/wp\/v2\/posts\/902\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eplglobal.verifinow.in\/es\/wp-json\/wp\/v2\/media\/891"}],"wp:attachment":[{"href":"https:\/\/eplglobal.verifinow.in\/es\/wp-json\/wp\/v2\/media?parent=902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eplglobal.verifinow.in\/es\/wp-json\/wp\/v2\/categories?post=902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eplglobal.verifinow.in\/es\/wp-json\/wp\/v2\/tags?post=902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3e7731db888a30e70e6e97. Config Timestamp: 2026-06-26 12:57:21 UTC, Cached Timestamp: 2026-07-15 07:26:14 UTC, Optimization Time: 4.09ms -->