{"id":913,"date":"2024-02-07T14:02:00","date_gmt":"2024-02-07T14:02:00","guid":{"rendered":"https:\/\/eplglobal.verifinow.in\/?p=913"},"modified":"2024-07-16T14:05:07","modified_gmt":"2024-07-16T14:05:07","slug":"epl-limited-q3-fy24-concall-audio","status":"publish","type":"post","link":"https:\/\/eplglobal.verifinow.in\/cn\/epl-limited-q3-fy24-concall-audio\/","title":{"rendered":"EPL \u6709\u9650\u516c\u53f8 24 \u8d22\u5e74\u7b2c\u4e09\u5b63\u5ea6\u80a1\u4e1c\u5927\u4f1a - \u97f3\u9891"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-913","post","type-post","status-publish","format-standard","hentry","category-multimedia"],"acf":[],"yoast_head":"\n<title>EPL Limited Q3 FY24 Concall \u2013 Audio - EPL - Leading the pack<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EPL Limited Q3 FY24 Concall \u2013 Audio - EPL - Leading the pack\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eplglobal.verifinow.in\/cn\/epl-limited-q3-fy24-concall-audio\/\" \/>\n<meta property=\"og:site_name\" content=\"EPL - Leading the pack\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EPLGlobalLimited\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-07T14:02:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-16T14:05:07+00:00\" \/>\n<meta name=\"author\" content=\"admin_eplwp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EPL_Limited\" \/>\n<meta name=\"twitter:site\" content=\"@EPL_Limited\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_eplwp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/epl-limited-q3-fy24-concall-audio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/epl-limited-q3-fy24-concall-audio\\\/\"},\"author\":{\"name\":\"admin_eplwp\",\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/#\\\/schema\\\/person\\\/1dcd283e3b2c8dd1cbb342b00411d36e\"},\"headline\":\"EPL Limited Q3 FY24 Concall \u2013 Audio\",\"datePublished\":\"2024-02-07T14:02:00+00:00\",\"dateModified\":\"2024-07-16T14:05:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/epl-limited-q3-fy24-concall-audio\\\/\"},\"wordCount\":6,\"publisher\":{\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/#organization\"},\"articleSection\":[\"Multimedia\"],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/epl-limited-q3-fy24-concall-audio\\\/\",\"url\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/epl-limited-q3-fy24-concall-audio\\\/\",\"name\":\"EPL Limited Q3 FY24 Concall \u2013 Audio - EPL - Leading the pack\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/#website\"},\"datePublished\":\"2024-02-07T14:02:00+00:00\",\"dateModified\":\"2024-07-16T14:05:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/epl-limited-q3-fy24-concall-audio\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eplglobal.verifinow.in\\\/epl-limited-q3-fy24-concall-audio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/epl-limited-q3-fy24-concall-audio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EPL Limited Q3 FY24 Concall \u2013 Audio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/#website\",\"url\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/\",\"name\":\"EPL\",\"description\":\"EPL ltd\",\"publisher\":{\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/#organization\",\"name\":\"EPL Ltd\",\"url\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/EPL-logo-300x207-1-3.png\",\"contentUrl\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/EPL-logo-300x207-1-3.png\",\"width\":300,\"height\":207,\"caption\":\"EPL Ltd\"},\"image\":{\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EPLGlobalLimited\",\"https:\\\/\\\/x.com\\\/EPL_Limited\",\"https:\\\/\\\/www.instagram.com\\\/epl_limited\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/epl-limited\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCciHlQEzUjUqievawSyoNcw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eplglobal.verifinow.in\\\/#\\\/schema\\\/person\\\/1dcd283e3b2c8dd1cbb342b00411d36e\",\"name\":\"admin_eplwp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f14e7ab5f443acaad94261e67d284b5c5212d1a38088925ac84f1633be102fe?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f14e7ab5f443acaad94261e67d284b5c5212d1a38088925ac84f1633be102fe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f14e7ab5f443acaad94261e67d284b5c5212d1a38088925ac84f1633be102fe?s=96&d=mm&r=g\",\"caption\":\"admin_eplwp\"},\"sameAs\":[\"https:\\\/\\\/eplglobal.verifinow.in\"]}]}<\/script>\n","yoast_head_json":{"title":"EPL Limited Q3 FY24 \u7535\u8bdd\u4f1a\u8bae \u2013 \u97f3\u9891 - EPL - \u9886\u5148\u7fa4\u96c4","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"zh_CN","og_type":"article","og_title":"EPL Limited Q3 FY24 Concall \u2013 Audio - EPL - Leading the pack","og_url":"https:\/\/eplglobal.verifinow.in\/cn\/epl-limited-q3-fy24-concall-audio\/","og_site_name":"EPL - Leading the pack","article_publisher":"https:\/\/www.facebook.com\/EPLGlobalLimited","article_published_time":"2024-02-07T14:02:00+00:00","article_modified_time":"2024-07-16T14:05:07+00:00","author":"admin_eplwp","twitter_card":"summary_large_image","twitter_creator":"@EPL_Limited","twitter_site":"@EPL_Limited","twitter_misc":{"\u4f5c\u8005":"admin_eplwp"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eplglobal.verifinow.in\/epl-limited-q3-fy24-concall-audio\/#article","isPartOf":{"@id":"https:\/\/eplglobal.verifinow.in\/epl-limited-q3-fy24-concall-audio\/"},"author":{"name":"admin_eplwp","@id":"https:\/\/eplglobal.verifinow.in\/#\/schema\/person\/1dcd283e3b2c8dd1cbb342b00411d36e"},"headline":"EPL Limited Q3 FY24 Concall \u2013 Audio","datePublished":"2024-02-07T14:02:00+00:00","dateModified":"2024-07-16T14:05:07+00:00","mainEntityOfPage":{"@id":"https:\/\/eplglobal.verifinow.in\/epl-limited-q3-fy24-concall-audio\/"},"wordCount":6,"publisher":{"@id":"https:\/\/eplglobal.verifinow.in\/#organization"},"articleSection":["Multimedia"],"inLanguage":"zh-Hans"},{"@type":"WebPage","@id":"https:\/\/eplglobal.verifinow.in\/epl-limited-q3-fy24-concall-audio\/","url":"https:\/\/eplglobal.verifinow.in\/epl-limited-q3-fy24-concall-audio\/","name":"EPL Limited Q3 FY24 \u7535\u8bdd\u4f1a\u8bae \u2013 \u97f3\u9891 - EPL - \u9886\u5148\u7fa4\u96c4","isPartOf":{"@id":"https:\/\/eplglobal.verifinow.in\/#website"},"datePublished":"2024-02-07T14:02:00+00:00","dateModified":"2024-07-16T14:05:07+00:00","breadcrumb":{"@id":"https:\/\/eplglobal.verifinow.in\/epl-limited-q3-fy24-concall-audio\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eplglobal.verifinow.in\/epl-limited-q3-fy24-concall-audio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/eplglobal.verifinow.in\/epl-limited-q3-fy24-concall-audio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eplglobal.verifinow.in\/"},{"@type":"ListItem","position":2,"name":"EPL Limited Q3 FY24 Concall \u2013 Audio"}]},{"@type":"WebSite","@id":"https:\/\/eplglobal.verifinow.in\/#website","url":"https:\/\/eplglobal.verifinow.in\/","name":"\u82f1\u8d85","description":"EPL \u6709\u9650\u516c\u53f8","publisher":{"@id":"https:\/\/eplglobal.verifinow.in\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eplglobal.verifinow.in\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/eplglobal.verifinow.in\/#organization","name":"\u82f1\u5b5a\u6559\u80b2\u6709\u9650\u516c\u53f8","url":"https:\/\/eplglobal.verifinow.in\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/eplglobal.verifinow.in\/#\/schema\/logo\/image\/","url":"https:\/\/eplglobal.verifinow.in\/wp-content\/uploads\/2024\/07\/EPL-logo-300x207-1-3.png","contentUrl":"https:\/\/eplglobal.verifinow.in\/wp-content\/uploads\/2024\/07\/EPL-logo-300x207-1-3.png","width":300,"height":207,"caption":"EPL Ltd"},"image":{"@id":"https:\/\/eplglobal.verifinow.in\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EPLGlobalLimited","https:\/\/x.com\/EPL_Limited","https:\/\/www.instagram.com\/epl_limited\/","https:\/\/www.linkedin.com\/company\/epl-limited\/","https:\/\/www.youtube.com\/channel\/UCciHlQEzUjUqievawSyoNcw"]},{"@type":"Person","@id":"https:\/\/eplglobal.verifinow.in\/#\/schema\/person\/1dcd283e3b2c8dd1cbb342b00411d36e","name":"\u7ba1\u7406\u5458","image":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/secure.gravatar.com\/avatar\/6f14e7ab5f443acaad94261e67d284b5c5212d1a38088925ac84f1633be102fe?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6f14e7ab5f443acaad94261e67d284b5c5212d1a38088925ac84f1633be102fe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f14e7ab5f443acaad94261e67d284b5c5212d1a38088925ac84f1633be102fe?s=96&d=mm&r=g","caption":"admin_eplwp"},"sameAs":["https:\/\/eplglobal.verifinow.in"]}]}},"_links":{"self":[{"href":"https:\/\/eplglobal.verifinow.in\/cn\/wp-json\/wp\/v2\/posts\/913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eplglobal.verifinow.in\/cn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eplglobal.verifinow.in\/cn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eplglobal.verifinow.in\/cn\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eplglobal.verifinow.in\/cn\/wp-json\/wp\/v2\/comments?post=913"}],"version-history":[{"count":0,"href":"https:\/\/eplglobal.verifinow.in\/cn\/wp-json\/wp\/v2\/posts\/913\/revisions"}],"wp:attachment":[{"href":"https:\/\/eplglobal.verifinow.in\/cn\/wp-json\/wp\/v2\/media?parent=913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eplglobal.verifinow.in\/cn\/wp-json\/wp\/v2\/categories?post=913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eplglobal.verifinow.in\/cn\/wp-json\/wp\/v2\/tags?post=913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3e7731db888a30e70e6e97. Config Timestamp: 2026-06-26 12:57:21 UTC, Cached Timestamp: 2026-07-15 09:59:59 UTC, Optimization Time: 5.59ms -->